{"id":37565,"date":"2019-12-19T17:33:07","date_gmt":"2019-12-19T16:33:07","guid":{"rendered":"https:\/\/www.autorita-trasporti.it\/?post_type=cpt_faq&#038;p=37565"},"modified":"2023-10-01T15:42:03","modified_gmt":"2023-10-01T13:42:03","slug":"nella-stazione-di-partenza-non-sono-presenti-biglietteria-ne-distributori-automatici-funzionanti-come-faccio-ad-acquistare-un-biglietto-ferroviario","status":"publish","type":"cpt_faq","link":"https:\/\/www.autorita-trasporti.it\/en\/cpt_faq\/nella-stazione-di-partenza-non-sono-presenti-biglietteria-ne-distributori-automatici-funzionanti-come-faccio-ad-acquistare-un-biglietto-ferroviario\/","title":{"rendered":"Nella stazione di partenza non sono presenti biglietteria, n\u00e9 distributori automatici funzionanti: come faccio ad acquistare un biglietto ferroviario?"},"content":{"rendered":"<p>In mancanza di biglietteria o biglietteria <em>self-service<\/em> nella stazione ferroviaria di partenza, i viaggiatori devono essere informati in stazione:<\/p>\n<ul style=\"list-style-type: disc;\">\n<li>della possibilit\u00e0 di acquistare un biglietto per telefono, via internet o a bordo del treno, e delle modalit\u00e0 di tali acquisti;<\/li>\n<li>della stazione ferroviaria o del luogo pi\u00f9 vicino in cui sono disponibili biglietterie e\/o biglietterie <em>self-service<\/em>.<\/li>\n<\/ul>\n<p>Se nella stazione di partenza non sono presenti biglietterie, biglietterie self-service accessibili e altri modi accessibili per acquistare un biglietto in anticipo, le persone con disabilit\u00e0 hanno diritto di acquistare biglietti a bordo dei treni senza maggiorazione.<\/p>\n<p>Per i treni ricompresi in contratti di servizio pubblico (ad esempio treni regionali, e molti <em>intercity<\/em>), nel caso di partenza da una stazione in cui non sia presente una biglietteria o un distributore automatico funzionante, l\u2019impresa di trasporto \u00e8 tenuta a consentire l\u2019acquisto del biglietto a bordo senza alcun sovrapprezzo.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"taxonomy_anno":[],"taxonomy_cat_faq":[394],"taxonomy_tag_cloud":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/cpt_faq\/37565"}],"collection":[{"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/cpt_faq"}],"about":[{"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/types\/cpt_faq"}],"version-history":[{"count":1,"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/cpt_faq\/37565\/revisions"}],"predecessor-version":[{"id":52483,"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/cpt_faq\/37565\/revisions\/52483"}],"wp:attachment":[{"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/media?parent=37565"}],"wp:term":[{"taxonomy":"taxonomy_anno","embeddable":true,"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/taxonomy_anno?post=37565"},{"taxonomy":"taxonomy_cat_faq","embeddable":true,"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/taxonomy_cat_faq?post=37565"},{"taxonomy":"taxonomy_tag_cloud","embeddable":true,"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/taxonomy_tag_cloud?post=37565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}