{"id":47403,"date":"2022-08-04T17:55:09","date_gmt":"2022-08-04T15:55:09","guid":{"rendered":"https:\/\/www.autorita-trasporti.it\/?post_type=cpt_delibera&#038;p=47403"},"modified":"2022-08-04T17:55:09","modified_gmt":"2022-08-04T15:55:09","slug":"delibera-n-136-2022","status":"publish","type":"cpt_delibera","link":"https:\/\/www.autorita-trasporti.it\/en\/delibere\/delibera-n-136-2022\/","title":{"rendered":"Delibera n. 136\/2022"},"content":{"rendered":"<p>Avvio di procedimento ai sensi del d.lgs. 129\/2015, recante \u201c<em>Disciplina sanzionatoria delle violazioni delle disposizioni del regolamento (UE) n. 1177\/2010, che modifica il regolamento (CE) n. 2006\/2004, relativo ai diritti dei passeggeri che viaggiano via mare e per vie navigabili interne<\/em>\u201d<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"taxonomy_anno":[467],"taxonomy_categoria":[221,228],"taxonomy_settore":[214],"taxonomy_tag_cloud":[343,347,344],"acf":[],"_links":{"self":[{"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/cpt_delibera\/47403"}],"collection":[{"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/cpt_delibera"}],"about":[{"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/types\/cpt_delibera"}],"version-history":[{"count":0,"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/cpt_delibera\/47403\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/media?parent=47403"}],"wp:term":[{"taxonomy":"taxonomy_anno","embeddable":true,"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/taxonomy_anno?post=47403"},{"taxonomy":"taxonomy_categoria","embeddable":true,"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/taxonomy_categoria?post=47403"},{"taxonomy":"taxonomy_settore","embeddable":true,"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/taxonomy_settore?post=47403"},{"taxonomy":"taxonomy_tag_cloud","embeddable":true,"href":"https:\/\/www.autorita-trasporti.it\/en\/wp-json\/wp\/v2\/taxonomy_tag_cloud?post=47403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}